{"id":3064,"date":"2020-03-12T16:54:58","date_gmt":"2020-03-12T16:54:58","guid":{"rendered":"https:\/\/www.barbaracupiti.com\/distantimauniti\/"},"modified":"2020-03-12T16:54:58","modified_gmt":"2020-03-12T16:54:58","slug":"distantimauniti","status":"publish","type":"post","link":"https:\/\/www.barbaracupiti.com\/en\/distantimauniti\/","title":{"rendered":"#distantimauniti"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Cari Tutti,<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Che momento difficile stiamo attraversando, non importa se siamo in Italia o in un altro Paese, \u00e8 difficile per il <i>nostro<\/i> Paese e per il settore delle vacanze-studio in particolare. Tutti noi stiamo lavorando duro per far s\u00ec che le cose continuino a funzionare il pi\u00f9 regolarmente possibile ma nessuno uscir\u00e0 indenne da questo momento.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Comunque, tutto ci\u00f2 che abbiamo fatto e che cerchiamo di continuare a fare per mantenere alto lo spirito e l\u2019entusiasmo ci servir\u00e0 ad essere pronti una volta che la situazione torner\u00e0 \u201cnormale\u201d.\u00a0<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Dobbiamo seguire le disposizioni per la Salute Pubblica, da parte nostra abbiamo incrementato le lezioni online mentre le traduzioni continuano ad essere consegnate regolarmente via email. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Anche gli incontri e le riunioni si tengono online. Voi sapete quanto sia poco tecnologica, traggo da questo momento l\u2019insegnamento all\u2019utilizzo di piattaforme diverse e pi\u00f9 prestanti per migliorare i momenti che condividiamo.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">So che anche per alcuni di Voi \u00e8 difficile, ma siamo <i>una forza<\/i> e ce la faremo! Siamo fortunati ad avere queste opportunit\u00e0, non ci resta altro da fare che usarle.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">E\u2019 difficile tenere alto il morale, il nostro cuore \u00e8 affranto per coloro che sono stati colpiti personalmente e ci auguriamo che essi ed i loro cari si rimettano presto \u2026 sia per la loro salute che economicamente.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">I migliori auguri e saluti,<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Barbara<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cari Tutti, Che momento difficile stiamo attraversando, non importa se siamo in Italia o in un altro Paese, \u00e8 difficile per il nostro Paese e per il settore delle vacanze-studio in particolare. Tutti noi stiamo lavorando duro per far s\u00ec che le cose continuino a funzionare il pi\u00f9 regolarmente possibile ma nessuno uscir\u00e0 indenne da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[33],"tags":[],"class_list":["post-3064","post","type-post","status-publish","format-standard","hentry","category-news-en"],"_links":{"self":[{"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/posts\/3064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/comments?post=3064"}],"version-history":[{"count":0,"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/posts\/3064\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/media?parent=3064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/categories?post=3064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.barbaracupiti.com\/en\/wp-json\/wp\/v2\/tags?post=3064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}